{"id":28278,"date":"2023-12-08T07:02:11","date_gmt":"2023-12-08T07:02:11","guid":{"rendered":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2.jpg"},"modified":"2023-12-08T07:02:11","modified_gmt":"2023-12-08T07:02:11","slug":"jpgkeskisuuri_residens_skolan_171017_34-2-2","status":"inherit","type":"attachment","link":"https:\/\/isku.com\/ru\/jpgkeskisuuri_residens_skolan_171017_34-2-2\/","title":{"rendered":"JPG+Keskisuuri_Residens_skolan_171017_34 (2)"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-28278","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2.jpg'><img decoding=\"async\" width=\"800\" height=\"528\" src=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-800x528.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-800x528.jpg 800w, https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-1000x659.jpg 1000w, https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-600x396.jpg 600w, https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-768x506.jpg 768w, https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-1536x1013.jpg 1536w, https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-500x330.jpg 500w, https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2.jpg 1800w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1800,"height":1187,"file":"2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2.jpg","filesize":1356204,"sizes":{"medium":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2-800x528.jpg","width":800,"height":528,"filesize":64991,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-800x528.jpg"},"large":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2-1000x659.jpg","width":1000,"height":659,"filesize":92182,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-1000x659.jpg"},"thumbnail":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2-600x396.jpg","width":600,"height":396,"filesize":43205,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-600x396.jpg"},"medium_large":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2-768x506.jpg","width":768,"height":506,"filesize":61680,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-768x506.jpg"},"1536x1536":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2-1536x1013.jpg","width":1536,"height":1013,"filesize":172653,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-1536x1013.jpg"},"woocommerce_thumbnail":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2-500x500.jpg","width":500,"height":500,"filesize":40303,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-500x500.jpg"},"woocommerce_single":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2-500x330.jpg","width":500,"height":330,"filesize":32988,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-500x330.jpg"},"woocommerce_gallery_thumbnail":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2-100x100.jpg","width":100,"height":100,"filesize":4161,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2-100x100.jpg"},"full":{"file":"JPGKeskisuuri_Residens_skolan_171017_34-2.jpg","width":1800,"height":1187,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/12\/JPGKeskisuuri_Residens_skolan_171017_34-2.jpg","filename":"JPGKeskisuuri_Residens_skolan_171017_34-2.jpg","filesize":1356204,"_links":{"self":[{"href":"https:\/\/isku.com\/ru\/wp-json\/wp\/v2\/media\/28278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isku.com\/ru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/isku.com\/ru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/isku.com\/ru\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/isku.com\/ru\/wp-json\/wp\/v2\/comments?post=28278"}]}}