{"id":26939,"date":"2023-11-16T11:40:39","date_gmt":"2023-11-16T11:40:39","guid":{"rendered":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference.jpg"},"modified":"2023-11-16T11:40:39","modified_gmt":"2023-11-16T11:40:39","slug":"when_microbes_matter__material_makes_the_difference-2","status":"inherit","type":"attachment","link":"https:\/\/isku.com\/fi\/when_microbes_matter__material_makes_the_difference-2\/","title":{"rendered":"When_microbes_matter__material_makes_the_difference"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-26939","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference.jpg'><img decoding=\"async\" width=\"735\" height=\"505\" src=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference.jpg 735w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference-600x412.jpg 600w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference-500x344.jpg 500w\" sizes=\"(max-width: 735px) 100vw, 735px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":735,"height":505,"file":"2023\/11\/When_microbes_matter__material_makes_the_difference.jpg","filesize":132617,"sizes":{"thumbnail":{"file":"When_microbes_matter__material_makes_the_difference-600x412.jpg","width":600,"height":412,"filesize":18993,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference-600x412.jpg"},"woocommerce_thumbnail":{"file":"When_microbes_matter__material_makes_the_difference-500x500.jpg","width":500,"height":500,"filesize":16363,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference-500x500.jpg"},"woocommerce_single":{"file":"When_microbes_matter__material_makes_the_difference-500x344.jpg","width":500,"height":344,"filesize":14955,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference-500x344.jpg"},"woocommerce_gallery_thumbnail":{"file":"When_microbes_matter__material_makes_the_difference-100x100.jpg","width":100,"height":100,"filesize":2575,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference-100x100.jpg"},"full":{"file":"When_microbes_matter__material_makes_the_difference.jpg","width":735,"height":505,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/When_microbes_matter__material_makes_the_difference.jpg","filename":"When_microbes_matter__material_makes_the_difference.jpg","filesize":132617,"_links":{"self":[{"href":"https:\/\/isku.com\/fi\/wp-json\/wp\/v2\/media\/26939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isku.com\/fi\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/isku.com\/fi\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/isku.com\/fi\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/isku.com\/fi\/wp-json\/wp\/v2\/comments?post=26939"}]}}