{"id":8284,"date":"2023-05-18T17:48:01","date_gmt":"2023-05-18T17:48:01","guid":{"rendered":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2.jpg"},"modified":"2023-05-18T17:48:01","modified_gmt":"2023-05-18T17:48:01","slug":"isku-mukula-rahi-nelio-interior-2-2","status":"inherit","type":"attachment","link":"https:\/\/isku.com\/en\/?attachment_id=8284#main","title":{"rendered":"isku-mukula-rahi-nelio-interior-2"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-8284","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2.jpg'><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-800x800.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-800x800.jpg 800w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-500x500.jpg 500w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-100x100.jpg 100w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-1000x1000.jpg 1000w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-280x280.jpg 280w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-768x768.jpg 768w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1080,"height":1080,"file":"2023\/05\/isku-mukula-rahi-nelio-interior-2.jpg","filesize":193306,"sizes":{"woocommerce_thumbnail":{"file":"isku-mukula-rahi-nelio-interior-2-500x500.jpg","width":500,"height":500,"filesize":44672,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-500x500.jpg"},"woocommerce_gallery_thumbnail":{"file":"isku-mukula-rahi-nelio-interior-2-100x100.jpg","width":100,"height":100,"filesize":3567,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-100x100.jpg"},"woocommerce_single":{"file":"isku-mukula-rahi-nelio-interior-2-500x500.jpg","width":500,"height":500,"filesize":44672,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-500x500.jpg"},"medium":{"file":"isku-mukula-rahi-nelio-interior-2-800x800.jpg","width":800,"height":800,"filesize":94749,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-800x800.jpg"},"large":{"file":"isku-mukula-rahi-nelio-interior-2-1000x1000.jpg","width":1000,"height":1000,"filesize":132172,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-1000x1000.jpg"},"thumbnail":{"file":"isku-mukula-rahi-nelio-interior-2-280x280.jpg","width":280,"height":280,"filesize":17402,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-280x280.jpg"},"medium_large":{"file":"isku-mukula-rahi-nelio-interior-2-768x768.jpg","width":768,"height":768,"filesize":89765,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2-768x768.jpg"},"full":{"file":"isku-mukula-rahi-nelio-interior-2.jpg","width":1080,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4637,"source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/isku-mukula-rahi-nelio-interior-2.jpg","filename":"isku-mukula-rahi-nelio-interior-2.jpg","filesize":193306,"_links":{"self":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/media\/8284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/comments?post=8284"}],"wp:attached-to":[{"embeddable":true,"post_type":"product","id":4637,"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/product\/4637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}