{"id":7854,"date":"2023-05-18T13:48:13","date_gmt":"2023-05-18T13:48:13","guid":{"rendered":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy.jpg"},"modified":"2023-05-18T13:48:13","modified_gmt":"2023-05-18T13:48:13","slug":"isku-mode-etulevy-2","status":"inherit","type":"attachment","link":"https:\/\/isku.com\/en\/isku-mode-etulevy-2\/","title":{"rendered":"ISKU-Mode-etulevy"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-7854","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy.jpg'><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-800x800.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-800x800.jpg 800w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-500x500.jpg 500w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-100x100.jpg 100w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-1000x1000.jpg 1000w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-280x280.jpg 280w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-768x768.jpg 768w, https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1080,"height":1080,"file":"2023\/05\/ISKU-Mode-etulevy.jpg","filesize":97714,"sizes":{"woocommerce_thumbnail":{"file":"ISKU-Mode-etulevy-500x500.jpg","width":500,"height":500,"filesize":37181,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-500x500.jpg"},"woocommerce_gallery_thumbnail":{"file":"ISKU-Mode-etulevy-100x100.jpg","width":100,"height":100,"filesize":3594,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-100x100.jpg"},"woocommerce_single":{"file":"ISKU-Mode-etulevy-500x500.jpg","width":500,"height":500,"filesize":37181,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-500x500.jpg"},"medium":{"file":"ISKU-Mode-etulevy-800x800.jpg","width":800,"height":800,"filesize":73281,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-800x800.jpg"},"large":{"file":"ISKU-Mode-etulevy-1000x1000.jpg","width":1000,"height":1000,"filesize":105295,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-1000x1000.jpg"},"thumbnail":{"file":"ISKU-Mode-etulevy-280x280.jpg","width":280,"height":280,"filesize":15380,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-280x280.jpg"},"medium_large":{"file":"ISKU-Mode-etulevy-768x768.jpg","width":768,"height":768,"filesize":69599,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy-768x768.jpg"},"full":{"file":"ISKU-Mode-etulevy.jpg","width":1080,"height":1080,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/05\/ISKU-Mode-etulevy.jpg","filename":"ISKU-Mode-etulevy.jpg","filesize":97714,"_links":{"self":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/media\/7854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/comments?post=7854"}]}}