{"id":25834,"date":"2023-11-04T16:43:24","date_gmt":"2023-11-04T16:43:24","guid":{"rendered":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119.jpg"},"modified":"2023-11-04T16:43:24","modified_gmt":"2023-11-04T16:43:24","slug":"jpgkeskisuuri_anssi_turpeinen_190119-2","status":"inherit","type":"attachment","link":"https:\/\/isku.com\/en\/jpgkeskisuuri_anssi_turpeinen_190119-2\/","title":{"rendered":"JPG+Keskisuuri_Anssi_Turpeinen_190119"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-25834","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119.jpg'><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-800x800.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-800x800.jpg 800w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-1000x1000.jpg 1000w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-600x600.jpg 600w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-768x768.jpg 768w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-1536x1536.jpg 1536w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-500x500.jpg 500w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-100x100.jpg 100w, https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119.jpg 1800w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1800,"height":1800,"file":"2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119.jpg","filesize":862801,"sizes":{"medium":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119-800x800.jpg","width":800,"height":800,"filesize":59111,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-800x800.jpg"},"large":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119-1000x1000.jpg","width":1000,"height":1000,"filesize":91028,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-1000x1000.jpg"},"thumbnail":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119-600x600.jpg","width":600,"height":600,"filesize":35355,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-600x600.jpg"},"medium_large":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119-768x768.jpg","width":768,"height":768,"filesize":54328,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-768x768.jpg"},"1536x1536":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119-1536x1536.jpg","width":1536,"height":1536,"filesize":200297,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-1536x1536.jpg"},"woocommerce_thumbnail":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119-500x500.jpg","width":500,"height":500,"filesize":24599,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-500x500.jpg"},"woocommerce_single":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119-500x500.jpg","width":500,"height":500,"filesize":24599,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-500x500.jpg"},"woocommerce_gallery_thumbnail":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119-100x100.jpg","width":100,"height":100,"filesize":2637,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119-100x100.jpg"},"full":{"file":"JPGKeskisuuri_Anssi_Turpeinen_190119.jpg","width":1800,"height":1800,"mime_type":"image\/jpeg","source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/isku.com\/wp-content\/uploads\/2023\/11\/JPGKeskisuuri_Anssi_Turpeinen_190119.jpg","filename":"JPGKeskisuuri_Anssi_Turpeinen_190119.jpg","filesize":862801,"_links":{"self":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/media\/25834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/isku.com\/en\/wp-json\/wp\/v2\/comments?post=25834"}]}}